{"id":24666,"date":"2026-05-06T13:28:40","date_gmt":"2026-05-06T11:28:40","guid":{"rendered":"https:\/\/www.luuks.nl\/?post_type=product&#038;p=24666"},"modified":"2026-05-06T13:37:55","modified_gmt":"2026-05-06T11:37:55","slug":"vibae-zuma-schoen-zwart","status":"publish","type":"product","link":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/","title":{"rendered":"VIBAe Zuma Schuh schwarz"},"content":{"rendered":"<p><strong> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<p>Leder VIBAe Zuma Schuh aus schwarzem Leder<\/p>\n<p>Gr\u00f6\u00dfe &#038; Passform: F\u00e4llt gr\u00f6\u00dfengerecht aus<\/p>\n<p>Alle <a href=\"https:\/\/www.luuks.nl\/de\/marke\/vibae\/\">VIBAe<\/a> Modelle bei LUUKS ansehen<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":24683,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[1802],"product_cat":[727,1358,724,1357],"product_tag":[1907],"class_list":{"0":"post-24666","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-vibae","7":"product_cat-herren","8":"product_cat-sandalen-pantoletten-herren","9":"product_cat-schuhe-herren","10":"product_cat-slipper-herren","11":"product_tag-warteliste","12":"pa_kleur-kakaobraun","13":"pa_maat-721","14":"pa_maat-751","15":"pa_maat-719","16":"pa_maat-722","17":"pa_maat-885","18":"pa_seizoen-lz2026","19":"desktop-align-center","20":"tablet-align-center","21":"mobile-align-center","22":"ast-product-gallery-layout-vertical","23":"ast-product-single-variable","25":"first","26":"instock","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIBAe Zuma Lederschuhe schwarz Leder | LUUKS Amsterdam<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die VIBAe Zuma Lederschuhe in schwarz bei LUUKS. Minimalistisches Design und hoher Komfort. Kaufen Sie online oder besuchen Sie unser Gesch\u00e4ft in Amsterdam.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIBAe Zuma Lederschuhe schwarz Leder | LUUKS Amsterdam\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die VIBAe Zuma Lederschuhe in schwarz bei LUUKS. Minimalistisches Design und hoher Komfort. Kaufen Sie online oder besuchen Sie unser Gesch\u00e4ft in Amsterdam.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/\" \/>\n<meta property=\"og:site_name\" content=\"LUUKS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T11:37:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.luuks.nl\/wp-content\/uploads\/2026\/05\/Vibae-Zuma-black-0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/\",\"url\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/\",\"name\":\"VIBAe Zuma Lederschuhe schwarz Leder | LUUKS Amsterdam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.luuks.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Vibae-Zuma-black-0.jpg\",\"datePublished\":\"2026-05-06T11:28:40+00:00\",\"dateModified\":\"2026-05-06T11:37:55+00:00\",\"description\":\"Entdecken Sie die VIBAe Zuma Lederschuhe in schwarz bei LUUKS. Minimalistisches Design und hoher Komfort. Kaufen Sie online oder besuchen Sie unser Gesch\u00e4ft in Amsterdam.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.luuks.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Vibae-Zuma-black-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.luuks.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Vibae-Zuma-black-0.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Vibae Zuma Schwarzes Leder\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/vibae-zuma-schoen-zwart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.luuks.nl\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VIBAe Zuma Schuh schwarz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/#website\",\"url\":\"https:\\\/\\\/www.luuks.nl\\\/\",\"name\":\"LUUKS\",\"description\":\"Voor schoen- en accessoire liefhebbers die kiezen voor stijl en kwaliteit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.luuks.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/#organization\",\"name\":\"LUUKS\",\"url\":\"https:\\\/\\\/www.luuks.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.luuks.nl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/LUUKS_LOGO_Red.svg\",\"contentUrl\":\"https:\\\/\\\/www.luuks.nl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/LUUKS_LOGO_Red.svg\",\"caption\":\"LUUKS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.luuks.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIBAe Zuma Lederschuhe schwarz Leder | LUUKS Amsterdam","description":"Entdecken Sie die VIBAe Zuma Lederschuhe in schwarz bei LUUKS. Minimalistisches Design und hoher Komfort. Kaufen Sie online oder besuchen Sie unser Gesch\u00e4ft in Amsterdam.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/","og_locale":"de_DE","og_type":"article","og_title":"VIBAe Zuma Lederschuhe schwarz Leder | LUUKS Amsterdam","og_description":"Entdecken Sie die VIBAe Zuma Lederschuhe in schwarz bei LUUKS. Minimalistisches Design und hoher Komfort. Kaufen Sie online oder besuchen Sie unser Gesch\u00e4ft in Amsterdam.","og_url":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/","og_site_name":"LUUKS","article_modified_time":"2026-05-06T11:37:55+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.luuks.nl\/wp-content\/uploads\/2026\/05\/Vibae-Zuma-black-0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/","url":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/","name":"VIBAe Zuma Lederschuhe schwarz Leder | LUUKS Amsterdam","isPartOf":{"@id":"https:\/\/www.luuks.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/#primaryimage"},"image":{"@id":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.luuks.nl\/wp-content\/uploads\/2026\/05\/Vibae-Zuma-black-0.jpg","datePublished":"2026-05-06T11:28:40+00:00","dateModified":"2026-05-06T11:37:55+00:00","description":"Entdecken Sie die VIBAe Zuma Lederschuhe in schwarz bei LUUKS. Minimalistisches Design und hoher Komfort. Kaufen Sie online oder besuchen Sie unser Gesch\u00e4ft in Amsterdam.","breadcrumb":{"@id":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/#primaryimage","url":"https:\/\/www.luuks.nl\/wp-content\/uploads\/2026\/05\/Vibae-Zuma-black-0.jpg","contentUrl":"https:\/\/www.luuks.nl\/wp-content\/uploads\/2026\/05\/Vibae-Zuma-black-0.jpg","width":1000,"height":1000,"caption":"Vibae Zuma Schwarzes Leder"},{"@type":"BreadcrumbList","@id":"https:\/\/www.luuks.nl\/de\/vibae-zuma-schoen-zwart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.luuks.nl\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.luuks.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"VIBAe Zuma Schuh schwarz"}]},{"@type":"WebSite","@id":"https:\/\/www.luuks.nl\/#website","url":"https:\/\/www.luuks.nl\/","name":"LUUKS","description":"Voor schoen- en accessoire liefhebbers die kiezen voor stijl en kwaliteit","publisher":{"@id":"https:\/\/www.luuks.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.luuks.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.luuks.nl\/#organization","name":"LUUKS","url":"https:\/\/www.luuks.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.luuks.nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.luuks.nl\/wp-content\/uploads\/2025\/11\/LUUKS_LOGO_Red.svg","contentUrl":"https:\/\/www.luuks.nl\/wp-content\/uploads\/2025\/11\/LUUKS_LOGO_Red.svg","caption":"LUUKS"},"image":{"@id":"https:\/\/www.luuks.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/product\/24666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/media\/24683"}],"wp:attachment":[{"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/media?parent=24666"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/product_brand?post=24666"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/product_cat?post=24666"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.luuks.nl\/de\/wp-json\/wp\/v2\/product_tag?post=24666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}